{"id":4679,"date":"2016-10-12T22:04:21","date_gmt":"2016-10-12T22:04:21","guid":{"rendered":"https:\/\/rosefdn.org\/latest\/grantees-advocating-for-clean-air-in-pittsburg-ca\/"},"modified":"2024-05-31T16:30:45","modified_gmt":"2024-05-31T16:30:45","slug":"beneficiarios-que-abogan-por-un-aire-limpio-en-pittsburg-ca","status":"publish","type":"news","link":"https:\/\/rosefdn.org\/es\/latest\/grantees-advocating-for-clean-air-in-pittsburg-ca\/","title":{"rendered":"Defensores del aire limpio en Pittsburg (California)"},"content":{"rendered":"<p><span style=\"font-weight: 400;\"><img decoding=\"async\" class=\"alignleft wp-image-28873\" src=\"\/wp-content\/uploads\/20160927_120530-e1476234156858-596x358.jpg\" width=\"450\" height=\"270\" \/>Para hacer frente a los problemas de calidad del aire en Pittsburg, se ha puesto en marcha una iniciativa biling\u00fce de un a\u00f1o de duraci\u00f3n llamada <\/span><span style=\"font-weight: 400;\">Proyecto de Defensores Comunitarios de la Calidad del Aire de Pittsburg<\/span><span style=\"font-weight: 400;\"> se financia con una subvenci\u00f3n del Distrito de Gesti\u00f3n de la Calidad del Aire del \u00c1rea de la Bah\u00eda. El objetivo del proyecto es formar a 200 miembros de la comunidad sobre la contaminaci\u00f3n atmosf\u00e9rica y sus repercusiones en la salud.  Se trata de una asociaci\u00f3n entre<\/span><span style=\"font-weight: 400;\"> La Cl\u00ednica de la Raza, Community Science Institute de Denny Larson, y Freedom Breathers con el apoyo de activistas locales. Y nos complace compartir que uno de esos activistas locales <\/span><b>activistas es un personal<\/b><span style=\"font-weight: 400;\">\u00a0miembro de la Fundaci\u00f3n Rose.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Pamela Arauz, Directora Administrativa de la fundaci\u00f3n y defensora del aire limpio en Pittsburg, California, participa en una <\/span><b>voluntariado como coformador <\/b><span style=\"font-weight: 400;\">en el proyecto de defensa del aire limpio. Pamela se involucr\u00f3 en la oposici\u00f3n al proyecto de infraestructuras energ\u00e9ticas WesPac en septiembre de 2013. De aprobarse, WesPac habr\u00eda estado a 15 minutos de su casa en Antioch. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">En diciembre de 2013, se llev\u00f3 a cabo un proyecto comunitario de vigilancia del aire que revel\u00f3 la contaminaci\u00f3n atmosf\u00e9rica, sus v\u00ednculos con la salud y otros problemas, como la ausencia de una estaci\u00f3n de vigilancia del aire muy necesaria. <\/span><a href=\"\/\/pittsburgdc.org\/wp-content\/uploads\/PittsburgAirSamplesReport_web.pdf\"><b>Puede leerlo todo aqu\u00ed.<\/b><\/a><\/p>\n<p><span style=\"font-weight: 400;\">WesPac intent\u00f3 transformar unas instalaciones de Pacific Gas &amp; Electric inactivas desde hace 15 a\u00f1os en un centro de almacenamiento, transferencia y transporte de 10 millones de galones diarios de crudo por ferrocarril, oleoducto, barco y barcaza. Esto habr\u00eda aumentado las emisiones t\u00f3xicas al aire y empeorado la calidad del aire de la zona. Sin embargo, la comunidad no iba a consentirlo. Entre la ca\u00edda mundial de los precios del petr\u00f3leo y el retraso del proyecto por parte de grupos de base locales preocupados e informados, grandes organizaciones sin \u00e1nimo de lucro y muchos activistas, en diciembre de 2015, el contratista retir\u00f3 la solicitud de permiso a la ciudad de Pittsburg.<\/span><\/p>\n<p><span style=\"font-weight: 400;\"> <img decoding=\"async\" class=\"alignright wp-image-28874\" src=\"\/wp-content\/uploads\/20160927_1004161-1-596x358.jpg\" alt=\"20160927_1004161\" width=\"450\" height=\"270\" \/>WesPac inspir\u00f3 a la comunidad para que se levantara y abriera los ojos ante las injusticias medioambientales que se comet\u00edan en su ciudad. Y el activismo por un aire limpio continu\u00f3 a trav\u00e9s del trabajo de Freedom Breather, un becario de Rose Foundation. Freedom Breather es un grupo de profesores de ciencias y alumnos del instituto de Pittsburg que, en enero de 2015, se reunieron para supervisar las condiciones de la calidad del aire en su ciudad. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">El Community Science Institute, Freedom Breathers y los activistas locales que luchan por la justicia medioambiental en Pittsburg han recibido el apoyo de la Rose Foundation en distintas fases de estos comprometidos esfuerzos de defensa de un aire limpio. Los socios de\u00a0<\/span><span style=\"font-weight: 400;\">Proyecto de Defensores Comunitarios de la Calidad del Aire de Pittsburg<\/span><span style=\"font-weight: 400;\">\u00a0<\/span><span style=\"font-weight: 400;\">est\u00e1n entusiasmados con este nuevo <\/span><span style=\"font-weight: 400;\">empe\u00f1o. El objetivo \u00faltimo es mejorar la calidad del aire para los m\u00e1s afectados, como ni\u00f1os, ancianos o personas con problemas respiratorios. <\/span><b>Le mantendremos informado a medida que se desarrolle este proyecto.<\/b><\/p>","protected":false},"excerpt":{"rendered":"<p>La calidad del aire se ha convertido en un tema cada vez m\u00e1s importante en el \u00c1rea de la Bah\u00eda, y las comunidades han expresado su opini\u00f3n. En Pittsburg (California), el personal y los beneficiarios de la Fundaci\u00f3n Rose se re\u00fanen para informar a los miembros de la comunidad sobre la calidad del aire cerca de sus hogares.<\/p>","protected":false},"featured_media":3667,"template":"","format":[],"categories":[82],"tags":[],"topic":[],"class_list":["post-4679","news","type-news","status-publish","has-post-thumbnail","hentry","category-news-features"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Grantees Advocating for Clean Air in Pittsburg, CA - Rose Foundation<\/title>\n<meta name=\"description\" content=\"Air quality has become an increasingly important issue around the Bay Area, and communities have expressed their voices. In Pittsburg, CA Rose Foundation staff and grantees are coming together to inform community members on air quality near their home.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/rosefdn.org\/es\/novedades\/beneficiarios-que-abogan-por-un-aire-limpio-en-pittsburg-ca\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Grantees Advocating for Clean Air in Pittsburg, CA - Rose Foundation\" \/>\n<meta property=\"og:description\" content=\"Air quality has become an increasingly important issue around the Bay Area, and communities have expressed their voices. In Pittsburg, CA Rose Foundation staff and grantees are coming together to inform community members on air quality near their home.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/rosefdn.org\/es\/novedades\/beneficiarios-que-abogan-por-un-aire-limpio-en-pittsburg-ca\/\" \/>\n<meta property=\"og:site_name\" content=\"Rose Foundation\" \/>\n<meta property=\"article:modified_time\" content=\"2024-05-31T16:30:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/rosefdn.org\/wp-content\/uploads\/20160927_130135.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1536\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/rosefdn.org\\\/latest\\\/grantees-advocating-for-clean-air-in-pittsburg-ca\\\/\",\"url\":\"https:\\\/\\\/rosefdn.org\\\/latest\\\/grantees-advocating-for-clean-air-in-pittsburg-ca\\\/\",\"name\":\"Grantees Advocating for Clean Air in Pittsburg, CA - Rose Foundation\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/rosefdn.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/rosefdn.org\\\/latest\\\/grantees-advocating-for-clean-air-in-pittsburg-ca\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/rosefdn.org\\\/latest\\\/grantees-advocating-for-clean-air-in-pittsburg-ca\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/rosefdn.org\\\/wp-content\\\/uploads\\\/20160927_130135.jpg\",\"datePublished\":\"2016-10-12T22:04:21+00:00\",\"dateModified\":\"2024-05-31T16:30:45+00:00\",\"description\":\"Air quality has become an increasingly important issue around the Bay Area, and communities have expressed their voices. In Pittsburg, CA Rose Foundation staff and grantees are coming together to inform community members on air quality near their home.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/rosefdn.org\\\/latest\\\/grantees-advocating-for-clean-air-in-pittsburg-ca\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/rosefdn.org\\\/latest\\\/grantees-advocating-for-clean-air-in-pittsburg-ca\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/rosefdn.org\\\/latest\\\/grantees-advocating-for-clean-air-in-pittsburg-ca\\\/#primaryimage\",\"url\":\"https:\\\/\\\/rosefdn.org\\\/wp-content\\\/uploads\\\/20160927_130135.jpg\",\"contentUrl\":\"https:\\\/\\\/rosefdn.org\\\/wp-content\\\/uploads\\\/20160927_130135.jpg\",\"width\":2560,\"height\":1536},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/rosefdn.org\\\/latest\\\/grantees-advocating-for-clean-air-in-pittsburg-ca\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/rosefdn.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Grantees Advocating for Clean Air in Pittsburg, CA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/rosefdn.org\\\/#website\",\"url\":\"https:\\\/\\\/rosefdn.org\\\/\",\"name\":\"Rose Foundation\",\"description\":\"Communities Flourish With Stewardship\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/rosefdn.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Becarios que abogan por un aire limpio en Pittsburg, CA - Rose Foundation","description":"La calidad del aire se ha convertido en un tema cada vez m\u00e1s importante en el \u00c1rea de la Bah\u00eda, y las comunidades han expresado su opini\u00f3n. En Pittsburg (California), el personal y los beneficiarios de la Fundaci\u00f3n Rose se re\u00fanen para informar a los miembros de la comunidad sobre la calidad del aire cerca de sus hogares.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/rosefdn.org\/es\/novedades\/beneficiarios-que-abogan-por-un-aire-limpio-en-pittsburg-ca\/","og_locale":"es_ES","og_type":"article","og_title":"Grantees Advocating for Clean Air in Pittsburg, CA - Rose Foundation","og_description":"Air quality has become an increasingly important issue around the Bay Area, and communities have expressed their voices. In Pittsburg, CA Rose Foundation staff and grantees are coming together to inform community members on air quality near their home.","og_url":"https:\/\/rosefdn.org\/es\/novedades\/beneficiarios-que-abogan-por-un-aire-limpio-en-pittsburg-ca\/","og_site_name":"Rose Foundation","article_modified_time":"2024-05-31T16:30:45+00:00","og_image":[{"width":2560,"height":1536,"url":"https:\/\/rosefdn.org\/wp-content\/uploads\/20160927_130135.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/rosefdn.org\/latest\/grantees-advocating-for-clean-air-in-pittsburg-ca\/","url":"https:\/\/rosefdn.org\/latest\/grantees-advocating-for-clean-air-in-pittsburg-ca\/","name":"Becarios que abogan por un aire limpio en Pittsburg, CA - Rose Foundation","isPartOf":{"@id":"https:\/\/rosefdn.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/rosefdn.org\/latest\/grantees-advocating-for-clean-air-in-pittsburg-ca\/#primaryimage"},"image":{"@id":"https:\/\/rosefdn.org\/latest\/grantees-advocating-for-clean-air-in-pittsburg-ca\/#primaryimage"},"thumbnailUrl":"https:\/\/rosefdn.org\/wp-content\/uploads\/20160927_130135.jpg","datePublished":"2016-10-12T22:04:21+00:00","dateModified":"2024-05-31T16:30:45+00:00","description":"La calidad del aire se ha convertido en un tema cada vez m\u00e1s importante en el \u00c1rea de la Bah\u00eda, y las comunidades han expresado su opini\u00f3n. En Pittsburg (California), el personal y los beneficiarios de la Fundaci\u00f3n Rose se re\u00fanen para informar a los miembros de la comunidad sobre la calidad del aire cerca de sus hogares.","breadcrumb":{"@id":"https:\/\/rosefdn.org\/latest\/grantees-advocating-for-clean-air-in-pittsburg-ca\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/rosefdn.org\/latest\/grantees-advocating-for-clean-air-in-pittsburg-ca\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/rosefdn.org\/latest\/grantees-advocating-for-clean-air-in-pittsburg-ca\/#primaryimage","url":"https:\/\/rosefdn.org\/wp-content\/uploads\/20160927_130135.jpg","contentUrl":"https:\/\/rosefdn.org\/wp-content\/uploads\/20160927_130135.jpg","width":2560,"height":1536},{"@type":"BreadcrumbList","@id":"https:\/\/rosefdn.org\/latest\/grantees-advocating-for-clean-air-in-pittsburg-ca\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/rosefdn.org\/"},{"@type":"ListItem","position":2,"name":"Grantees Advocating for Clean Air in Pittsburg, CA"}]},{"@type":"WebSite","@id":"https:\/\/rosefdn.org\/#website","url":"https:\/\/rosefdn.org\/","name":"Fundaci\u00f3n Rosa","description":"Las comunidades florecen con la administraci\u00f3n","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/rosefdn.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/rosefdn.org\/es\/wp-json\/wp\/v2\/news\/4679","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rosefdn.org\/es\/wp-json\/wp\/v2\/news"}],"about":[{"href":"https:\/\/rosefdn.org\/es\/wp-json\/wp\/v2\/types\/news"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rosefdn.org\/es\/wp-json\/wp\/v2\/media\/3667"}],"wp:attachment":[{"href":"https:\/\/rosefdn.org\/es\/wp-json\/wp\/v2\/media?parent=4679"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rosefdn.org\/es\/wp-json\/wp\/v2\/categories?post=4679"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rosefdn.org\/es\/wp-json\/wp\/v2\/tags?post=4679"},{"taxonomy":"topic","embeddable":true,"href":"https:\/\/rosefdn.org\/es\/wp-json\/wp\/v2\/topic?post=4679"},{"taxonomy":"format","embeddable":true,"href":"https:\/\/rosefdn.org\/es\/wp-json\/wp\/v2\/format?post=4679"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}